{"id":5531,"date":"2013-03-30T10:09:58","date_gmt":"2013-03-30T17:09:58","guid":{"rendered":"http:\/\/www.evelynanddenny.com\/blog\/wp-content\/uploads\/2013\/03\/163499_155244097973914_1643248911_n1-Copy.jpg"},"modified":"2013-03-30T10:09:58","modified_gmt":"2013-03-30T17:09:58","slug":"163499_155244097973914_1643248911_n1-copy","status":"inherit","type":"attachment","link":"https:\/\/evelynanddenny.com\/blog\/amy-instructr-nite-32913\/163499_155244097973914_1643248911_n1-copy\/","title":{"rendered":"163499_155244097973914_1643248911_n[1] &#8211; Copy"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-5531","attachment","type-attachment","status-inherit","hentry"],"a3_pvc":{"activated":false,"total_views":0,"today_views":0},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/evelynanddenny.com\/blog\/wp-content\/uploads\/2013\/03\/163499_155244097973914_1643248911_n1-Copy.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/evelynanddenny.com\/blog\/wp-content\/uploads\/2013\/03\/163499_155244097973914_1643248911_n1-Copy-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/evelynanddenny.com\/blog\/wp-content\/uploads\/2013\/03\/163499_155244097973914_1643248911_n1-Copy-300x225.jpg 300w, https:\/\/evelynanddenny.com\/blog\/wp-content\/uploads\/2013\/03\/163499_155244097973914_1643248911_n1-Copy-150x112.jpg 150w, https:\/\/evelynanddenny.com\/blog\/wp-content\/uploads\/2013\/03\/163499_155244097973914_1643248911_n1-Copy.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"960","height":"720","hwstring_small":"height='96' width='128'","file":"2013\/03\/163499_155244097973914_1643248911_n1-Copy.jpg","sizes":{"thumbnail":{"file":"163499_155244097973914_1643248911_n1-Copy-150x112.jpg","width":"150","height":"112","source_url":"https:\/\/evelynanddenny.com\/blog\/wp-content\/uploads\/2013\/03\/163499_155244097973914_1643248911_n1-Copy-150x112.jpg"},"medium":{"file":"163499_155244097973914_1643248911_n1-Copy-300x225.jpg","width":"300","height":"225","source_url":"https:\/\/evelynanddenny.com\/blog\/wp-content\/uploads\/2013\/03\/163499_155244097973914_1643248911_n1-Copy-300x225.jpg"},"post-thumbnail":{"file":"163499_155244097973914_1643248911_n1-Copy-940x198.jpg","width":"940","height":"198","source_url":"https:\/\/evelynanddenny.com\/blog\/wp-content\/uploads\/2013\/03\/163499_155244097973914_1643248911_n1-Copy-940x198.jpg"},"full":{"file":"163499_155244097973914_1643248911_n1-Copy.jpg","width":960,"height":720,"mime_type":"image\/jpeg","source_url":"https:\/\/evelynanddenny.com\/blog\/wp-content\/uploads\/2013\/03\/163499_155244097973914_1643248911_n1-Copy.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":5516,"source_url":"https:\/\/evelynanddenny.com\/blog\/wp-content\/uploads\/2013\/03\/163499_155244097973914_1643248911_n1-Copy.jpg","_links":{"self":[{"href":"https:\/\/evelynanddenny.com\/blog\/wp-json\/wp\/v2\/media\/5531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evelynanddenny.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/evelynanddenny.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/evelynanddenny.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/evelynanddenny.com\/blog\/wp-json\/wp\/v2\/comments?post=5531"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":5516,"href":"https:\/\/evelynanddenny.com\/blog\/wp-json\/wp\/v2\/pages\/5516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}