{"id":3362,"date":"2012-11-24T09:50:36","date_gmt":"2012-11-24T17:50:36","guid":{"rendered":"http:\/\/www.evelynanddenny.com\/blog\/wp-content\/uploads\/2012\/11\/Awwwwww.jpg"},"modified":"2012-11-24T09:50:36","modified_gmt":"2012-11-24T17:50:36","slug":"awwwwww","status":"inherit","type":"attachment","link":"https:\/\/evelynanddenny.com\/blog\/bnb-black-frid-dane-112312\/awwwwww\/","title":{"rendered":"Awww"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-3362","attachment","type-attachment","status-inherit","hentry"],"a3_pvc":{"activated":false,"total_views":0,"today_views":0},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/evelynanddenny.com\/blog\/wp-content\/uploads\/2012\/11\/Awwwwww.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/evelynanddenny.com\/blog\/wp-content\/uploads\/2012\/11\/Awwwwww-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"Awww\" srcset=\"https:\/\/evelynanddenny.com\/blog\/wp-content\/uploads\/2012\/11\/Awwwwww-300x225.jpg 300w, https:\/\/evelynanddenny.com\/blog\/wp-content\/uploads\/2012\/11\/Awwwwww-150x112.jpg 150w, https:\/\/evelynanddenny.com\/blog\/wp-content\/uploads\/2012\/11\/Awwwwww.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Awww <a href=\"https:\/\/evelynanddenny.com\/blog\/bnb-black-frid-dane-112312\/awwwwww\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n"},"alt_text":"Awww","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"960","height":"720","hwstring_small":"height='96' width='128'","file":"2012\/11\/Awwwwww.jpg","sizes":{"thumbnail":{"file":"Awwwwww-150x112.jpg","width":"150","height":"112","source_url":"https:\/\/evelynanddenny.com\/blog\/wp-content\/uploads\/2012\/11\/Awwwwww-150x112.jpg"},"medium":{"file":"Awwwwww-300x225.jpg","width":"300","height":"225","source_url":"https:\/\/evelynanddenny.com\/blog\/wp-content\/uploads\/2012\/11\/Awwwwww-300x225.jpg"},"post-thumbnail":{"file":"Awwwwww-940x198.jpg","width":"940","height":"198","source_url":"https:\/\/evelynanddenny.com\/blog\/wp-content\/uploads\/2012\/11\/Awwwwww-940x198.jpg"},"full":{"file":"Awwwwww.jpg","width":960,"height":720,"mime_type":"image\/jpeg","source_url":"https:\/\/evelynanddenny.com\/blog\/wp-content\/uploads\/2012\/11\/Awwwwww.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":3361,"source_url":"https:\/\/evelynanddenny.com\/blog\/wp-content\/uploads\/2012\/11\/Awwwwww.jpg","_links":{"self":[{"href":"https:\/\/evelynanddenny.com\/blog\/wp-json\/wp\/v2\/media\/3362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evelynanddenny.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/evelynanddenny.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/evelynanddenny.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/evelynanddenny.com\/blog\/wp-json\/wp\/v2\/comments?post=3362"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":3361,"href":"https:\/\/evelynanddenny.com\/blog\/wp-json\/wp\/v2\/pages\/3361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}